{"id":11540,"date":"2026-08-05T17:55:45","date_gmt":"2026-08-05T17:55:45","guid":{"rendered":"https:\/\/lisbonpubliclaw.pt\/?post_type=projetos&#038;p=11540"},"modified":"2026-08-05T17:56:19","modified_gmt":"2026-08-05T17:56:19","slug":"arquivos-professor-doutor-jorge-miranda","status":"publish","type":"projetos","link":"https:\/\/lisbonpubliclaw.pt\/en\/projetos\/arquivos-professor-doutor-jorge-miranda\/","title":{"rendered":"Arquivos Professor Doutor Jorge Miranda"},"content":{"rendered":"","protected":false},"template":"","meta":{"imagem-do-projeto":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/05\/projetos.png","investigador-responsavel":["1755"],"investigador-lpl":["1741","1750"],"investigadores-externos":"Ant\u00f3nio de Ara\u00fajo (NOVA FCSH) &amp; Andr\u00e9 Moz Caldas (FDUL)","consultores":"","sumario-do-projecto":"O projeto visa catalogar, arquivar e publicitar em suporte inform\u00e1tico toda a documenta\u00e7\u00e3o com relev\u00e2ncia pol\u00edtica e constitucional do acervo pessoal do Professor Doutor Jorge Miranda, abrangendo, n\u00e3o apenas a documenta\u00e7\u00e3o que se encontra na posse deste \u00faltimo, mas tamb\u00e9m na posse de terceiros e ainda em arquivos de institui\u00e7\u00f5es p\u00fablicas e privadas, de modo a divulgar o pensamento jur\u00eddico e pol\u00edtico do mestre de Direito Constitucional e documentar a sua interven\u00e7\u00e3o na constru\u00e7\u00e3o das bases da III Rep\u00fablica Constitucional.","objectivos-do-projeto":"<p>- Alcan\u00e7ar uma exposi\u00e7\u00e3o e cataloga\u00e7\u00e3o sistem\u00e1tica da obra do Prof. Doutor Jorge Miranda, abrangendo a sua produ\u00e7\u00e3o acad\u00e9mica e a sua interven\u00e7\u00e3o pol\u00edtica.<\/p>\r\n<p>- Promover a divulga\u00e7\u00e3o do pensamento e do percurso pol\u00edtico do Prof. Doutor Jorge Miranda.<\/p>\r\n<p>- Tratar e organizar o acervo de acordo com os princ\u00edpios das ci\u00eancias arquiv\u00edsticas e da informa\u00e7\u00e3o e documenta\u00e7\u00e3o.<\/p>\r\n<p>- Refor\u00e7ar a colabora\u00e7\u00e3o com a Biblioteca da Faculdade de Direito no tratamento e valoriza\u00e7\u00e3o dos temas e materiais integrados no projeto.<\/p>\r\n<p>- Valorizar os instrumentos, recursos e plataformas digitais da Biblioteca, tornando a obra do Prof. Doutor Jorge Miranda mais acess\u00edvel ao p\u00fablico.<\/p>\r\n<p>\u00a0<\/p>\r\n<p>\u00a0<\/p>","relevancia":"O Professor Doutor Jorge Miranda \u00e9 uma figura central no pensamento pol\u00edtico-constitucional em Portugal na base da Constitui\u00e7\u00e3o de 1976, importando sistematizar e disponibilizar em obedi\u00eancia a crit\u00e9rios cient\u00edficos para o p\u00fablico acad\u00e9mico toda a sua atua\u00e7\u00e3o e interven\u00e7\u00e3o, n\u00e3o apenas no plano jur\u00eddico, mas tamb\u00e9m c\u00edvico e pol\u00edtico. Para al\u00e9m de ser destinado ao p\u00fablico acad\u00e9mico, o projeto visa tamb\u00e9m tornar acess\u00edvel ao p\u00fablico em geral o pensamento e a atua\u00e7\u00e3o de um dos principais constituintes e, bem assim, a atividade da Assembleia Constituinte e a vida pol\u00edtica no per\u00edodo imediatamente subsequente \u00e0 Revolu\u00e7\u00e3o do 25 de abril de 1976.","financiamento":"24 meses","estado-projeto":["Em Curso"],"link_para_pagina_do_projeto":"","hub":""},"cluster":[],"grupo-de-investigacao":[10],"class_list":["post-11540","projetos","type-projetos","status-publish","hentry","grupo-de-investigacao-direito-constitucional-e-ciencia-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Professor Doutor Jorge Miranda - Lisbon Public Law<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lisbonpubliclaw.pt\/en\/projetos\/arquivos-professor-doutor-jorge-miranda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Professor Doutor Jorge Miranda - Lisbon Public Law\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lisbonpubliclaw.pt\/en\/projetos\/arquivos-professor-doutor-jorge-miranda\/\" \/>\n<meta property=\"og:site_name\" content=\"Lisbon Public Law\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-05T17:56:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/projetos\\\/arquivos-professor-doutor-jorge-miranda\\\/\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/projetos\\\/arquivos-professor-doutor-jorge-miranda\\\/\",\"name\":\"Arquivos Professor Doutor Jorge Miranda - Lisbon Public Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#website\"},\"datePublished\":\"2026-08-05T17:55:45+00:00\",\"dateModified\":\"2026-08-05T17:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/projetos\\\/arquivos-professor-doutor-jorge-miranda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lisbonpubliclaw.pt\\\/projetos\\\/arquivos-professor-doutor-jorge-miranda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/projetos\\\/arquivos-professor-doutor-jorge-miranda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projetos\",\"item\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/projetos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arquivos Professor Doutor Jorge Miranda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#website\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\",\"name\":\"Lisbon Public Law\",\"description\":\"Public Law Research Centre in Lisbon\",\"publisher\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#organization\",\"name\":\"Lisbon Public Law\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg\",\"width\":354,\"height\":354,\"caption\":\"Lisbon Public Law\"},\"image\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Professor Doutor Jorge Miranda - Lisbon Public Law","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lisbonpubliclaw.pt\/en\/projetos\/arquivos-professor-doutor-jorge-miranda\/","og_locale":"en_US","og_type":"article","og_title":"Arquivos Professor Doutor Jorge Miranda - Lisbon Public Law","og_url":"https:\/\/lisbonpubliclaw.pt\/en\/projetos\/arquivos-professor-doutor-jorge-miranda\/","og_site_name":"Lisbon Public Law","article_modified_time":"2026-08-05T17:56:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lisbonpubliclaw.pt\/projetos\/arquivos-professor-doutor-jorge-miranda\/","url":"https:\/\/lisbonpubliclaw.pt\/projetos\/arquivos-professor-doutor-jorge-miranda\/","name":"Arquivos Professor Doutor Jorge Miranda - Lisbon Public Law","isPartOf":{"@id":"https:\/\/lisbonpubliclaw.pt\/#website"},"datePublished":"2026-08-05T17:55:45+00:00","dateModified":"2026-08-05T17:56:19+00:00","breadcrumb":{"@id":"https:\/\/lisbonpubliclaw.pt\/projetos\/arquivos-professor-doutor-jorge-miranda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lisbonpubliclaw.pt\/projetos\/arquivos-professor-doutor-jorge-miranda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lisbonpubliclaw.pt\/projetos\/arquivos-professor-doutor-jorge-miranda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lisbonpubliclaw.pt\/"},{"@type":"ListItem","position":2,"name":"Projetos","item":"https:\/\/lisbonpubliclaw.pt\/projetos\/"},{"@type":"ListItem","position":3,"name":"Arquivos Professor Doutor Jorge Miranda"}]},{"@type":"WebSite","@id":"https:\/\/lisbonpubliclaw.pt\/#website","url":"https:\/\/lisbonpubliclaw.pt\/","name":"Lisbon Public Law","description":"Public Law Research Centre in Lisbon","publisher":{"@id":"https:\/\/lisbonpubliclaw.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lisbonpubliclaw.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lisbonpubliclaw.pt\/#organization","name":"Lisbon Public Law","url":"https:\/\/lisbonpubliclaw.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lisbonpubliclaw.pt\/#\/schema\/logo\/image\/","url":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg","contentUrl":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg","width":354,"height":354,"caption":"Lisbon Public Law"},"image":{"@id":"https:\/\/lisbonpubliclaw.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/projetos\/11540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/projetos"}],"about":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/types\/projetos"}],"wp:attachment":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/media?parent=11540"}],"wp:term":[{"taxonomy":"cluster","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/cluster?post=11540"},{"taxonomy":"grupo-de-investigacao","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/grupo-de-investigacao?post=11540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}