{"id":7012,"date":"2024-10-01T16:22:49","date_gmt":"2024-10-01T16:22:49","guid":{"rendered":"https:\/\/lisbonpubliclaw.pt\/?post_type=blog&#038;p=7012"},"modified":"2024-11-11T16:26:51","modified_gmt":"2024-11-11T16:26:51","slug":"tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa","status":"publish","type":"blog","link":"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/","title":{"rendered":"Constitutional Court rules unconstitutional interpretative norm that provided for retroactive application of stamp duty on transactions between banking entities"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><br><br>TC \u2013 Case No. 55\/2023; Ruling No. 503\/2024<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Through Ruling No. 503\/2024, in Plenary, the Constitutional Court pointed out the unconstitutionality of a norm arising from an interpretative provision that established the retroactive application of Stamp Duty on transactions between banking entities involving card operations at ATMs and a multilateral interchange fee. This was an abstract review process following the previous ruling of the same norm as unconstitutional in three distinct cases of concrete review.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The decision is based on the constitutionality control of the norm that mandated Stamp Duty to apply to \u201ccommissions and payments for financial services\u201d that, until that date, were not covered, arising from Article 154 of Law No. 7-A\/2016, of March 30, (State Budget for 2016), in the part that attributed an interpretative nature to the wording given by Article 153 of that Law to Item 17.3.4 of the General Stamp Duty Table (TGIS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In turn, the wording of Item No. 17.3.4 of the General Stamp Duty Table was amended by Article 153 of the mentioned Law. The provision that Stamp Duty would apply to \u201c17 \u2013 Financial operations: (\u2026) 17.3.4 \u2013 Other commissions and payments for financial services... 4%\u201d was changed to indicate its application to \u201c17.3.4 - Other commissions and payments for financial services, including fees related to card-based payment transactions... 4%.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The underlying issue of the ruling concerns the constitutional review of interpretative norms in tax matters. Regarding interpretative norms, the Court stated that \u201cin contrast to innovative law, they aim or declare to \u2018intend to establish only the correct meaning of a prior normative act,\u2019 not creating \u2018new rights, but rather seeking to clarify the \u2018correct\u2019 meaning of pre-existing law.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The ruling noted that \u201cparagraph 3 of Article 103 of the Constitution does not automatically and absolutely prohibit the adoption of interpretative laws in tax matters, even if unfavourable to their recipients.\u201d However, there must be control regarding compliance with the non-retroactivity rule concerning \u201cinnovative norms to which the legislator, abusing the qualification as interpretative, seeks to assign authentically retroactive effectiveness,\u201d as observed in this case.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Court concluded that, although it was facing an interpretative law, there was an intent to innovate regarding the collection of a tax with retroactive application, in violation of paragraph 3 of Article 103 of the Constitution of the Republic.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Therefore, the Court decided to \u201cdeclare the unconstitutionality, with general binding effect, of the norm in Article 154 of Law No. 7-A\/2016, of March 30, in the part where it assigns an interpretative character to the wording given by Article 153 of that Law to Item 17.3.4 of the TGIS, determining that amounts charged between banking entities, prior to the entry into force of that Law, for card transactions at ATMs and as a multilateral interchange fee, are covered by this item, in violation of the prohibition against creating retroactive taxes established in Article 103, paragraph 3, of the Constitution.\u201d It is important to highlight that there was a dissenting opinion by Councillor Ant\u00f3nio Ascens\u00e3o Ramos. The dissent primarily argued that the new wording given to item 17.3.4 of the TGIS by Article 153 of Law No. 7-A\/2016, of March 30, could not be considered a \u201cmaterially innovative\u201d norm, as it cannot be considered that the previous normative provision did not address the incidence of tax on \u201cTMI commissions (Multilateral Interchange Fee) and TSC (Merchant Service Fee)\u201d and that such understanding could not be extracted from the legal framework in force until that point.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We invite everyone to follow the <a href=\"https:\/\/www.instagram.com\/objustica_constitucional\/\">Observat\u00f3rio <\/a>on social media for more relevant and up-to-date content on Constitutional Justice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The full text of the ruling is available <a href=\"http:\/\/www.tribunalconstitucional.pt\/tc\/acordaos\/20240503.html\">here<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"template":"","meta":[],"categoria-blog-observatorio":[80,82],"cluster":[51],"grupo-de-investigacao":[],"class_list":["post-7012","blog","type-blog","status-publish","hentry","categoria-blog-observatorio-direito_constitucional","categoria-blog-observatorio-direito_fiscal","cluster-observatorio-de-justica-constitucional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias - Lisbon Public Law<\/title>\n<meta name=\"description\" content=\"Por meio do Ac\u00f3rd\u00e3o n.\u00ba 503\/2024, em Plen\u00e1rio, o Tribunal Constitucional apontou a inconstitucionalidade da norma decorrente de norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre entre entidades banc\u00e1rias por opera\u00e7\u00f5es com cart\u00f5es em caixas autom\u00e1ticas e a t\u00edtulo de taxa multilateral de interc\u00e2mbio. Tratou-se de um processo de fiscaliza\u00e7\u00e3o abstrata ap\u00f3s o julgamento da mesma norma como inconstitucional, em tr\u00eas casos distintos, em fiscaliza\u00e7\u00e3o concreta. A decis\u00e3o tem por base o controlo de constitucionalidade quanto \u00e0 norma que determinou que o Imposto do Selo incidisse sobre \u201ccomiss\u00f5es e contrapresta\u00e7\u00f5es por servi\u00e7os financeiros\u201d que, at\u00e9 a data, n\u00e3o se encontravam abrangidas, decorrente do artigo 154.\u00ba da Lei n.\u00ba 7-A\/2016, de 30 de mar\u00e7o, (Or\u00e7amento do Estado para 2016) na parte em que, atribuiu car\u00e1ter interpretativo \u00e0 reda\u00e7\u00e3o dada pelo artigo 153.\u00ba dessa Lei \u00e0 Verba 17.3.4 da Tabela Geral do Imposto do Selo (TGIS)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias - Lisbon Public Law\" \/>\n<meta property=\"og:description\" content=\"Por meio do Ac\u00f3rd\u00e3o n.\u00ba 503\/2024, em Plen\u00e1rio, o Tribunal Constitucional apontou a inconstitucionalidade da norma decorrente de norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre entre entidades banc\u00e1rias por opera\u00e7\u00f5es com cart\u00f5es em caixas autom\u00e1ticas e a t\u00edtulo de taxa multilateral de interc\u00e2mbio. Tratou-se de um processo de fiscaliza\u00e7\u00e3o abstrata ap\u00f3s o julgamento da mesma norma como inconstitucional, em tr\u00eas casos distintos, em fiscaliza\u00e7\u00e3o concreta. A decis\u00e3o tem por base o controlo de constitucionalidade quanto \u00e0 norma que determinou que o Imposto do Selo incidisse sobre \u201ccomiss\u00f5es e contrapresta\u00e7\u00f5es por servi\u00e7os financeiros\u201d que, at\u00e9 a data, n\u00e3o se encontravam abrangidas, decorrente do artigo 154.\u00ba da Lei n.\u00ba 7-A\/2016, de 30 de mar\u00e7o, (Or\u00e7amento do Estado para 2016) na parte em que, atribuiu car\u00e1ter interpretativo \u00e0 reda\u00e7\u00e3o dada pelo artigo 153.\u00ba dessa Lei \u00e0 Verba 17.3.4 da Tabela Geral do Imposto do Selo (TGIS)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Lisbon Public Law\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T16:26:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\\\/\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\\\/\",\"name\":\"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias - Lisbon Public Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#website\"},\"datePublished\":\"2024-10-01T16:22:49+00:00\",\"dateModified\":\"2024-11-11T16:26:51+00:00\",\"description\":\"Por meio do Ac\u00f3rd\u00e3o n.\u00ba 503\\\/2024, em Plen\u00e1rio, o Tribunal Constitucional apontou a inconstitucionalidade da norma decorrente de norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre entre entidades banc\u00e1rias por opera\u00e7\u00f5es com cart\u00f5es em caixas autom\u00e1ticas e a t\u00edtulo de taxa multilateral de interc\u00e2mbio. Tratou-se de um processo de fiscaliza\u00e7\u00e3o abstrata ap\u00f3s o julgamento da mesma norma como inconstitucional, em tr\u00eas casos distintos, em fiscaliza\u00e7\u00e3o concreta. A decis\u00e3o tem por base o controlo de constitucionalidade quanto \u00e0 norma que determinou que o Imposto do Selo incidisse sobre \u201ccomiss\u00f5es e contrapresta\u00e7\u00f5es por servi\u00e7os financeiros\u201d que, at\u00e9 a data, n\u00e3o se encontravam abrangidas, decorrente do artigo 154.\u00ba da Lei n.\u00ba 7-A\\\/2016, de 30 de mar\u00e7o, (Or\u00e7amento do Estado para 2016) na parte em que, atribuiu car\u00e1ter interpretativo \u00e0 reda\u00e7\u00e3o dada pelo artigo 153.\u00ba dessa Lei \u00e0 Verba 17.3.4 da Tabela Geral do Imposto do Selo (TGIS)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#website\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\",\"name\":\"Lisbon Public Law\",\"description\":\"Public Law Research Centre in Lisbon\",\"publisher\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#organization\",\"name\":\"Lisbon Public Law\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg\",\"width\":354,\"height\":354,\"caption\":\"Lisbon Public Law\"},\"image\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias - Lisbon Public Law","description":"Por meio do Ac\u00f3rd\u00e3o n.\u00ba 503\/2024, em Plen\u00e1rio, o Tribunal Constitucional apontou a inconstitucionalidade da norma decorrente de norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre entre entidades banc\u00e1rias por opera\u00e7\u00f5es com cart\u00f5es em caixas autom\u00e1ticas e a t\u00edtulo de taxa multilateral de interc\u00e2mbio. Tratou-se de um processo de fiscaliza\u00e7\u00e3o abstrata ap\u00f3s o julgamento da mesma norma como inconstitucional, em tr\u00eas casos distintos, em fiscaliza\u00e7\u00e3o concreta. A decis\u00e3o tem por base o controlo de constitucionalidade quanto \u00e0 norma que determinou que o Imposto do Selo incidisse sobre \u201ccomiss\u00f5es e contrapresta\u00e7\u00f5es por servi\u00e7os financeiros\u201d que, at\u00e9 a data, n\u00e3o se encontravam abrangidas, decorrente do artigo 154.\u00ba da Lei n.\u00ba 7-A\/2016, de 30 de mar\u00e7o, (Or\u00e7amento do Estado para 2016) na parte em que, atribuiu car\u00e1ter interpretativo \u00e0 reda\u00e7\u00e3o dada pelo artigo 153.\u00ba dessa Lei \u00e0 Verba 17.3.4 da Tabela Geral do Imposto do Selo (TGIS)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/","og_locale":"en_US","og_type":"article","og_title":"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias - Lisbon Public Law","og_description":"Por meio do Ac\u00f3rd\u00e3o n.\u00ba 503\/2024, em Plen\u00e1rio, o Tribunal Constitucional apontou a inconstitucionalidade da norma decorrente de norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre entre entidades banc\u00e1rias por opera\u00e7\u00f5es com cart\u00f5es em caixas autom\u00e1ticas e a t\u00edtulo de taxa multilateral de interc\u00e2mbio. Tratou-se de um processo de fiscaliza\u00e7\u00e3o abstrata ap\u00f3s o julgamento da mesma norma como inconstitucional, em tr\u00eas casos distintos, em fiscaliza\u00e7\u00e3o concreta. A decis\u00e3o tem por base o controlo de constitucionalidade quanto \u00e0 norma que determinou que o Imposto do Selo incidisse sobre \u201ccomiss\u00f5es e contrapresta\u00e7\u00f5es por servi\u00e7os financeiros\u201d que, at\u00e9 a data, n\u00e3o se encontravam abrangidas, decorrente do artigo 154.\u00ba da Lei n.\u00ba 7-A\/2016, de 30 de mar\u00e7o, (Or\u00e7amento do Estado para 2016) na parte em que, atribuiu car\u00e1ter interpretativo \u00e0 reda\u00e7\u00e3o dada pelo artigo 153.\u00ba dessa Lei \u00e0 Verba 17.3.4 da Tabela Geral do Imposto do Selo (TGIS)","og_url":"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/","og_site_name":"Lisbon Public Law","article_modified_time":"2024-11-11T16:26:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/","url":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/","name":"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias - Lisbon Public Law","isPartOf":{"@id":"https:\/\/lisbonpubliclaw.pt\/#website"},"datePublished":"2024-10-01T16:22:49+00:00","dateModified":"2024-11-11T16:26:51+00:00","description":"Por meio do Ac\u00f3rd\u00e3o n.\u00ba 503\/2024, em Plen\u00e1rio, o Tribunal Constitucional apontou a inconstitucionalidade da norma decorrente de norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre entre entidades banc\u00e1rias por opera\u00e7\u00f5es com cart\u00f5es em caixas autom\u00e1ticas e a t\u00edtulo de taxa multilateral de interc\u00e2mbio. Tratou-se de um processo de fiscaliza\u00e7\u00e3o abstrata ap\u00f3s o julgamento da mesma norma como inconstitucional, em tr\u00eas casos distintos, em fiscaliza\u00e7\u00e3o concreta. A decis\u00e3o tem por base o controlo de constitucionalidade quanto \u00e0 norma que determinou que o Imposto do Selo incidisse sobre \u201ccomiss\u00f5es e contrapresta\u00e7\u00f5es por servi\u00e7os financeiros\u201d que, at\u00e9 a data, n\u00e3o se encontravam abrangidas, decorrente do artigo 154.\u00ba da Lei n.\u00ba 7-A\/2016, de 30 de mar\u00e7o, (Or\u00e7amento do Estado para 2016) na parte em que, atribuiu car\u00e1ter interpretativo \u00e0 reda\u00e7\u00e3o dada pelo artigo 153.\u00ba dessa Lei \u00e0 Verba 17.3.4 da Tabela Geral do Imposto do Selo (TGIS)","breadcrumb":{"@id":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-de-natureza-interpretativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lisbonpubliclaw.pt\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/lisbonpubliclaw.pt\/blog\/"},{"@type":"ListItem","position":3,"name":"Tribunal Constitucional julga inconstitucional norma de natureza interpretativa que previa a incid\u00eancia retroativa do Imposto do Selo sobre transa\u00e7\u00f5es entre entidades banc\u00e1rias"}]},{"@type":"WebSite","@id":"https:\/\/lisbonpubliclaw.pt\/#website","url":"https:\/\/lisbonpubliclaw.pt\/","name":"Lisbon Public Law","description":"Public Law Research Centre in Lisbon","publisher":{"@id":"https:\/\/lisbonpubliclaw.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lisbonpubliclaw.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lisbonpubliclaw.pt\/#organization","name":"Lisbon Public Law","url":"https:\/\/lisbonpubliclaw.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lisbonpubliclaw.pt\/#\/schema\/logo\/image\/","url":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg","contentUrl":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg","width":354,"height":354,"caption":"Lisbon Public Law"},"image":{"@id":"https:\/\/lisbonpubliclaw.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/blog\/7012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/media?parent=7012"}],"wp:term":[{"taxonomy":"categoria-blog-observatorio","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/categoria-blog-observatorio?post=7012"},{"taxonomy":"cluster","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/cluster?post=7012"},{"taxonomy":"grupo-de-investigacao","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/grupo-de-investigacao?post=7012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}