{"id":7005,"date":"2024-10-18T14:49:30","date_gmt":"2024-10-18T14:49:30","guid":{"rendered":"https:\/\/lisbonpubliclaw.pt\/?post_type=blog&#038;p=7005"},"modified":"2024-11-08T14:54:50","modified_gmt":"2024-11-08T14:54:50","slug":"tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade","status":"publish","type":"blog","link":"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/","title":{"rendered":"Constitutional Court Rules Unconstitutional the Provision Creating the Solidarity Surcharge on the Banking Sector"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><br><br>TC \u2013 Case No. 405\/2023; Ruling No. 469\/2024 <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On June 19, 2024, the 1st Section of the Constitutional Court, in a non-unanimous vote, ruled the provision creating the Solidarity Surcharge on the Banking Sector (ASSB) unconstitutional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The issue in question was the constitutionality of the provision contained in Article 21(1)(a) of <a href=\"https:\/\/diariodarepublica.pt\/dr\/legislacao-consolidada\/lei\/2020-138851745\">Law No. 27-A\/2020<\/a>of July 24, in the part referring to the calculation of the tax for the first half of 2020, as well as the provisions contained in Articles 1(2), 2, and 3(1)(a) of the Regime creating the ASSB, contained in Annex VI of <a href=\"https:\/\/diariodarepublica.pt\/dr\/legislacao-consolidada\/lei\/2020-138851745\">Law No. 27-A\/2020<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The ASSB applies to credit institutions whose principal place of management and effective administration is in Portuguese territory, branches in Portugal of credit institutions whose principal place of management is not in Portugal, and branches in Portugal of credit institutions with principal and effective headquarters outside national territory. This tax applies to entities not subject to Value Added Tax (VAT).<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">The ASSB is levied on the liabilities of banking sector entities, as per Article 4 of Annex VI of Law No. 27-A\/2020. The liabilities of these entities are defined as \u201cthe total of the items recognized on the balance sheet that, regardless of their form or modality, represent a debt to third parties.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Constitutional Court considered that the ASSB has the legal nature of a tax, and therefore is subject to the principle of non-retroactivity in tax matters, under Article 103(3) of the <a href=\"https:\/\/www.tribunalconstitucional.pt\/tc\/crp.html\">Portuguese Constitution<\/a>. In this regard, the provision stipulates that <em>the surcharge must be calculated \"with reference to the semiannual average of the final balances of each month corresponding to the accounts for the first half of 2020, and, therefore, the taxable event occurs before the law came into force, which happened the day after its publication,\u201d which does not comply with the constitutional rule of non-retroactivity.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Ruling No. 469\/2024 also found a violation of the principle of tax equality. In this regard, it was emphasized that the ASSB aims to reinforce the financing mechanisms of the social security system, as compensation for the VAT exemption applicable to most financial services and operations, and it applies to credit institutions based in Portuguese territory and branches or subsidiaries in Portugal of credit institutions headquartered outside Portuguese territory. The exclusive application of the ASSB to credit institutions was unjustified, as it was not possible to \"objectively determine the differentiation criterion that led the legislator to subject credit institutions to a special tax on the banking sector, nor is it possible to discern its real justification.\" Thus, the ASSB was characterized as \"an arbitrary differentiation in that the criterion used does not show a minimum of coherence nor is it materially justified.\"<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Finally, the decision addressed the violation of the principle of contributive capacity, as the tax did not concern any mode of income taxation but merely \"the subjection to tax of a part of the components of liabilities,\" and \"the lack of correspondence between the ASSB and a concrete index of contributive capacity valuation jeopardizes the constitutional viability of the tax,\u201d as well as the absence of a relationship \"between the real incidence of the tax and factors that might reveal a greater contributive capacity, when it is certain, as previously stated, that the tax allocation criterion, in this case, corresponds to a logic of solidarity based on the false assumption that credit institutions can bear an increase in tax burden because they are exempt from VAT on the financial services they provide.\"<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As a result, the mentioned provisions of <a href=\"https:\/\/diariodarepublica.pt\/dr\/legislacao-consolidada\/lei\/2020-138851745\">Law No. 27-A\/2020<\/a> were deemed unconstitutional for violating the principle of prohibition of tax retroactivity, under Article 103(3) of the <a href=\"https:\/\/www.tribunalconstitucional.pt\/tc\/crp.html\">Portuguese Constitution<\/a>, as well as the principles of equality, in the dimension of prohibition of arbitrariness, and contributive capacity, as a consequence of the principle of tax equality.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We invite everyone to follow the <a href=\"https:\/\/www.instagram.com\/objustica_constitucional\/\">Observat\u00f3rio <\/a>on social media for more relevant and up-to-date content on Constitutional Justice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The full text of the ruling is available <a href=\"http:\/\/www.tribunalconstitucional.pt\/tc\/acordaos\/20240469.html\">here<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"template":"","meta":[],"categoria-blog-observatorio":[80,82],"cluster":[51],"grupo-de-investigacao":[],"class_list":["post-7005","blog","type-blog","status-publish","hentry","categoria-blog-observatorio-direito_constitucional","categoria-blog-observatorio-direito_fiscal","cluster-observatorio-de-justica-constitucional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio - Lisbon Public Law<\/title>\n<meta name=\"description\" content=\"Em julgamento do \u00faltimo dia 19 de junho de 2024, a 1\u00aa Sec\u00e7\u00e3o do Tribunal Constitucional, em vota\u00e7\u00e3o n\u00e3o un\u00e2nime, decidiu pela inconstitucionalidade de norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio (ASSB). A mat\u00e9ria suscitada trata da inconstitucionalidade da norma contida nos artigos 21.\u00ba, n.\u00ba 1, al\u00ednea a), da Lei n.\u00ba 27-A\/2020, de 24 de julho, no segmento que se refere ao c\u00e1lculo do imposto relativo ao primeiro semestre de 2020; bem como das normas contidas nos artigos 1.\u00ba, n.\u00ba 2, 2.\u00ba e 3.\u00ba, n.\u00ba 1, al\u00ednea a), do Regime que cria o ASSB, contido no Anexo VI da Lei n.\u00ba 27-A\/2020. O ASSB incidiria sobre as institui\u00e7\u00f5es de cr\u00e9dito cuja sede principal e efetiva da administra\u00e7\u00e3o se encontre em territ\u00f3rio portugu\u00eas, as filiais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito que n\u00e3o tenham a sua sede principal em Portugal, e as sucursais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito com sede principal e efetiva fora do territ\u00f3rio nacional. Trata-se de tributo que incide sobre entidades n\u00e3o alcan\u00e7adas pelo Imposto sobre Valor Acrescentado (IVA).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio - Lisbon Public Law\" \/>\n<meta property=\"og:description\" content=\"Em julgamento do \u00faltimo dia 19 de junho de 2024, a 1\u00aa Sec\u00e7\u00e3o do Tribunal Constitucional, em vota\u00e7\u00e3o n\u00e3o un\u00e2nime, decidiu pela inconstitucionalidade de norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio (ASSB). A mat\u00e9ria suscitada trata da inconstitucionalidade da norma contida nos artigos 21.\u00ba, n.\u00ba 1, al\u00ednea a), da Lei n.\u00ba 27-A\/2020, de 24 de julho, no segmento que se refere ao c\u00e1lculo do imposto relativo ao primeiro semestre de 2020; bem como das normas contidas nos artigos 1.\u00ba, n.\u00ba 2, 2.\u00ba e 3.\u00ba, n.\u00ba 1, al\u00ednea a), do Regime que cria o ASSB, contido no Anexo VI da Lei n.\u00ba 27-A\/2020. O ASSB incidiria sobre as institui\u00e7\u00f5es de cr\u00e9dito cuja sede principal e efetiva da administra\u00e7\u00e3o se encontre em territ\u00f3rio portugu\u00eas, as filiais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito que n\u00e3o tenham a sua sede principal em Portugal, e as sucursais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito com sede principal e efetiva fora do territ\u00f3rio nacional. Trata-se de tributo que incide sobre entidades n\u00e3o alcan\u00e7adas pelo Imposto sobre Valor Acrescentado (IVA).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/\" \/>\n<meta property=\"og:site_name\" content=\"Lisbon Public Law\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-08T14:54:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\\\/\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\\\/\",\"name\":\"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio - Lisbon Public Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#website\"},\"datePublished\":\"2024-10-18T14:49:30+00:00\",\"dateModified\":\"2024-11-08T14:54:50+00:00\",\"description\":\"Em julgamento do \u00faltimo dia 19 de junho de 2024, a 1\u00aa Sec\u00e7\u00e3o do Tribunal Constitucional, em vota\u00e7\u00e3o n\u00e3o un\u00e2nime, decidiu pela inconstitucionalidade de norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio (ASSB). A mat\u00e9ria suscitada trata da inconstitucionalidade da norma contida nos artigos 21.\u00ba, n.\u00ba 1, al\u00ednea a), da Lei n.\u00ba 27-A\\\/2020, de 24 de julho, no segmento que se refere ao c\u00e1lculo do imposto relativo ao primeiro semestre de 2020; bem como das normas contidas nos artigos 1.\u00ba, n.\u00ba 2, 2.\u00ba e 3.\u00ba, n.\u00ba 1, al\u00ednea a), do Regime que cria o ASSB, contido no Anexo VI da Lei n.\u00ba 27-A\\\/2020. O ASSB incidiria sobre as institui\u00e7\u00f5es de cr\u00e9dito cuja sede principal e efetiva da administra\u00e7\u00e3o se encontre em territ\u00f3rio portugu\u00eas, as filiais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito que n\u00e3o tenham a sua sede principal em Portugal, e as sucursais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito com sede principal e efetiva fora do territ\u00f3rio nacional. Trata-se de tributo que incide sobre entidades n\u00e3o alcan\u00e7adas pelo Imposto sobre Valor Acrescentado (IVA).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#website\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\",\"name\":\"Lisbon Public Law\",\"description\":\"Public Law Research Centre in Lisbon\",\"publisher\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#organization\",\"name\":\"Lisbon Public Law\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg\",\"width\":354,\"height\":354,\"caption\":\"Lisbon Public Law\"},\"image\":{\"@id\":\"https:\\\/\\\/lisbonpubliclaw.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio - Lisbon Public Law","description":"Em julgamento do \u00faltimo dia 19 de junho de 2024, a 1\u00aa Sec\u00e7\u00e3o do Tribunal Constitucional, em vota\u00e7\u00e3o n\u00e3o un\u00e2nime, decidiu pela inconstitucionalidade de norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio (ASSB). A mat\u00e9ria suscitada trata da inconstitucionalidade da norma contida nos artigos 21.\u00ba, n.\u00ba 1, al\u00ednea a), da Lei n.\u00ba 27-A\/2020, de 24 de julho, no segmento que se refere ao c\u00e1lculo do imposto relativo ao primeiro semestre de 2020; bem como das normas contidas nos artigos 1.\u00ba, n.\u00ba 2, 2.\u00ba e 3.\u00ba, n.\u00ba 1, al\u00ednea a), do Regime que cria o ASSB, contido no Anexo VI da Lei n.\u00ba 27-A\/2020. O ASSB incidiria sobre as institui\u00e7\u00f5es de cr\u00e9dito cuja sede principal e efetiva da administra\u00e7\u00e3o se encontre em territ\u00f3rio portugu\u00eas, as filiais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito que n\u00e3o tenham a sua sede principal em Portugal, e as sucursais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito com sede principal e efetiva fora do territ\u00f3rio nacional. Trata-se de tributo que incide sobre entidades n\u00e3o alcan\u00e7adas pelo Imposto sobre Valor Acrescentado (IVA).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/","og_locale":"en_US","og_type":"article","og_title":"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio - Lisbon Public Law","og_description":"Em julgamento do \u00faltimo dia 19 de junho de 2024, a 1\u00aa Sec\u00e7\u00e3o do Tribunal Constitucional, em vota\u00e7\u00e3o n\u00e3o un\u00e2nime, decidiu pela inconstitucionalidade de norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio (ASSB). A mat\u00e9ria suscitada trata da inconstitucionalidade da norma contida nos artigos 21.\u00ba, n.\u00ba 1, al\u00ednea a), da Lei n.\u00ba 27-A\/2020, de 24 de julho, no segmento que se refere ao c\u00e1lculo do imposto relativo ao primeiro semestre de 2020; bem como das normas contidas nos artigos 1.\u00ba, n.\u00ba 2, 2.\u00ba e 3.\u00ba, n.\u00ba 1, al\u00ednea a), do Regime que cria o ASSB, contido no Anexo VI da Lei n.\u00ba 27-A\/2020. O ASSB incidiria sobre as institui\u00e7\u00f5es de cr\u00e9dito cuja sede principal e efetiva da administra\u00e7\u00e3o se encontre em territ\u00f3rio portugu\u00eas, as filiais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito que n\u00e3o tenham a sua sede principal em Portugal, e as sucursais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito com sede principal e efetiva fora do territ\u00f3rio nacional. Trata-se de tributo que incide sobre entidades n\u00e3o alcan\u00e7adas pelo Imposto sobre Valor Acrescentado (IVA).","og_url":"https:\/\/lisbonpubliclaw.pt\/en\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/","og_site_name":"Lisbon Public Law","article_modified_time":"2024-11-08T14:54:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/","url":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/","name":"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio - Lisbon Public Law","isPartOf":{"@id":"https:\/\/lisbonpubliclaw.pt\/#website"},"datePublished":"2024-10-18T14:49:30+00:00","dateModified":"2024-11-08T14:54:50+00:00","description":"Em julgamento do \u00faltimo dia 19 de junho de 2024, a 1\u00aa Sec\u00e7\u00e3o do Tribunal Constitucional, em vota\u00e7\u00e3o n\u00e3o un\u00e2nime, decidiu pela inconstitucionalidade de norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio (ASSB). A mat\u00e9ria suscitada trata da inconstitucionalidade da norma contida nos artigos 21.\u00ba, n.\u00ba 1, al\u00ednea a), da Lei n.\u00ba 27-A\/2020, de 24 de julho, no segmento que se refere ao c\u00e1lculo do imposto relativo ao primeiro semestre de 2020; bem como das normas contidas nos artigos 1.\u00ba, n.\u00ba 2, 2.\u00ba e 3.\u00ba, n.\u00ba 1, al\u00ednea a), do Regime que cria o ASSB, contido no Anexo VI da Lei n.\u00ba 27-A\/2020. O ASSB incidiria sobre as institui\u00e7\u00f5es de cr\u00e9dito cuja sede principal e efetiva da administra\u00e7\u00e3o se encontre em territ\u00f3rio portugu\u00eas, as filiais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito que n\u00e3o tenham a sua sede principal em Portugal, e as sucursais em Portugal de institui\u00e7\u00f5es de cr\u00e9dito com sede principal e efetiva fora do territ\u00f3rio nacional. Trata-se de tributo que incide sobre entidades n\u00e3o alcan\u00e7adas pelo Imposto sobre Valor Acrescentado (IVA).","breadcrumb":{"@id":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lisbonpubliclaw.pt\/blog\/tribunal-constitucional-julga-inconstitucional-norma-do-regime-adicional-de-solidariedade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lisbonpubliclaw.pt\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/lisbonpubliclaw.pt\/blog\/"},{"@type":"ListItem","position":3,"name":"Tribunal Constitucional julga inconstitucional norma do Regime que cria o Adicional de Solidariedade sobre o Setor Banc\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/lisbonpubliclaw.pt\/#website","url":"https:\/\/lisbonpubliclaw.pt\/","name":"Lisbon Public Law","description":"Public Law Research Centre in Lisbon","publisher":{"@id":"https:\/\/lisbonpubliclaw.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lisbonpubliclaw.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lisbonpubliclaw.pt\/#organization","name":"Lisbon Public Law","url":"https:\/\/lisbonpubliclaw.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lisbonpubliclaw.pt\/#\/schema\/logo\/image\/","url":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg","contentUrl":"https:\/\/lisbonpubliclaw.pt\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-19-at-11.01.50-1.jpeg","width":354,"height":354,"caption":"Lisbon Public Law"},"image":{"@id":"https:\/\/lisbonpubliclaw.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/blog\/7005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/media?parent=7005"}],"wp:term":[{"taxonomy":"categoria-blog-observatorio","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/categoria-blog-observatorio?post=7005"},{"taxonomy":"cluster","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/cluster?post=7005"},{"taxonomy":"grupo-de-investigacao","embeddable":true,"href":"https:\/\/lisbonpubliclaw.pt\/en\/wp-json\/wp\/v2\/grupo-de-investigacao?post=7005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}